{"id":102268,"date":"2025-02-23T14:04:23","date_gmt":"2025-02-23T13:04:23","guid":{"rendered":"https:\/\/peletizadoras.net\/catalogo-maquinas-proceso-peletizado\/sin%20categor\u00eda\/planta-peletizadora-media-1-plt200-400\/"},"modified":"2026-02-04T17:42:54","modified_gmt":"2026-02-04T16:42:54","slug":"planta-peletizadora-media-1-plt200-400","status":"publish","type":"product","link":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/","title":{"rendered":"Planta Peletizadora Media 1 PLT200\/400"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div><strong>EQUIPO PROFESIONAL PARA FABRICAR P\u00c9LET<\/strong><\/div>\n<div><\/div>\n<div>Con la nueva Planta Media 1 PLT200\/400 es posible fabricar p\u00e9let de manera industrial con un ahorro de espacio e inversi\u00f3n gracias a su disposici\u00f3n reducida y con cierto grado de autonom\u00eda, ya que los equipos incluidos preparan el material (desde astilla G30 a serr\u00edn) seg\u00fan lo requerido por la peletizadora.<\/div>\n<div><\/div>\n<div>Nuestras plantas peletizadoras tienen la particularidad de ser MODULARES, de manera que pueden a\u00f1adirse tantos elementos como prefieran o necesiten nuestros clientes. Los elementos que el cliente incluya finalmente en su planta de peletizado dependera\u0301 de sus necesidades, preferencias y del estado en que se encuentre la materia prima. <\/div>\n<p><em>* Las fotograf\u00edas se corresponden a configuraciones orientativas. Posibilidad de realizar diferentes configuraciones. <\/em><\/p>\n","protected":false},"featured_media":102102,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[101,100],"product_tag":[],"class_list":{"0":"post-102268","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-configuraciones","7":"product_cat-equipos-industriales","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Planta Peletizadora Media 1 PLT200\/400 - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet<\/title>\n<meta name=\"description\" content=\"Con la Planta Peletizadora Media PLT400\/800 es posible fabricar p\u00e9let de manera industrial desde serr\u00edn con los equipos indispensables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planta Peletizadora Media 1 PLT200\/400 - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\" \/>\n<meta property=\"og:description\" content=\"Con la Planta Peletizadora Media PLT400\/800 es posible fabricar p\u00e9let de manera industrial desde serr\u00edn con los equipos indispensables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EcofricaliaSostenible\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T16:42:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/planta-linea-pellet-pelet-peletizadora-media-1-plt400-800-destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@_ecofricalia\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-industriales\\\/configuraciones\\\/planta-peletizadora-media-1-plt200-400\\\/\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-industriales\\\/configuraciones\\\/planta-peletizadora-media-1-plt200-400\\\/\",\"name\":\"Planta Peletizadora Media 1 PLT200\\\/400 - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-industriales\\\/configuraciones\\\/planta-peletizadora-media-1-plt200-400\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-industriales\\\/configuraciones\\\/planta-peletizadora-media-1-plt200-400\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/planta-linea-pellet-pelet-peletizadora-media-1-plt400-800-destacada.jpg\",\"datePublished\":\"2025-02-23T13:04:23+00:00\",\"dateModified\":\"2026-02-04T16:42:54+00:00\",\"description\":\"Con la Planta Peletizadora Media PLT400\\\/800 es posible fabricar p\u00e9let de manera industrial desde serr\u00edn con los equipos indispensables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-industriales\\\/configuraciones\\\/planta-peletizadora-media-1-plt200-400\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-industriales\\\/configuraciones\\\/planta-peletizadora-media-1-plt200-400\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-industriales\\\/configuraciones\\\/planta-peletizadora-media-1-plt200-400\\\/#primaryimage\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/planta-linea-pellet-pelet-peletizadora-media-1-plt400-800-destacada.jpg\",\"contentUrl\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/planta-linea-pellet-pelet-peletizadora-media-1-plt400-800-destacada.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-industriales\\\/configuraciones\\\/planta-peletizadora-media-1-plt200-400\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/peletizadoras.net\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Planta Peletizadora Media 1 PLT200\\\/400\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#website\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/\",\"name\":\"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\",\"description\":\"Plantas y L\u00edneas industriales de peletizaci\u00f3n y m\u00e1quinas de fabricaci\u00f3n de pellet\",\"publisher\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#organization\",\"name\":\"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-ecofricalia-tapasweb.png\",\"contentUrl\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-ecofricalia-tapasweb.png\",\"width\":881,\"height\":418,\"caption\":\"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\"},\"image\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EcofricaliaSostenible\",\"https:\\\/\\\/x.com\\\/_ecofricalia\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCCvdG5pWUGvH4G5wP8TXuPw\",\"https:\\\/\\\/www.instagram.com\\\/ecofricalia_sostenible\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planta Peletizadora Media 1 PLT200\/400 - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","description":"Con la Planta Peletizadora Media PLT400\/800 es posible fabricar p\u00e9let de manera industrial desde serr\u00edn con los equipos indispensables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/","og_locale":"es_ES","og_type":"article","og_title":"Planta Peletizadora Media 1 PLT200\/400 - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","og_description":"Con la Planta Peletizadora Media PLT400\/800 es posible fabricar p\u00e9let de manera industrial desde serr\u00edn con los equipos indispensables.","og_url":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/","og_site_name":"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","article_publisher":"https:\/\/www.facebook.com\/EcofricaliaSostenible","article_modified_time":"2026-02-04T16:42:54+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/planta-linea-pellet-pelet-peletizadora-media-1-plt400-800-destacada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@_ecofricalia","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/","url":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/","name":"Planta Peletizadora Media 1 PLT200\/400 - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","isPartOf":{"@id":"https:\/\/peletizadoras.net\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/#primaryimage"},"image":{"@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/#primaryimage"},"thumbnailUrl":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/planta-linea-pellet-pelet-peletizadora-media-1-plt400-800-destacada.jpg","datePublished":"2025-02-23T13:04:23+00:00","dateModified":"2026-02-04T16:42:54+00:00","description":"Con la Planta Peletizadora Media PLT400\/800 es posible fabricar p\u00e9let de manera industrial desde serr\u00edn con los equipos indispensables.","breadcrumb":{"@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/#primaryimage","url":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/planta-linea-pellet-pelet-peletizadora-media-1-plt400-800-destacada.jpg","contentUrl":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/planta-linea-pellet-pelet-peletizadora-media-1-plt400-800-destacada.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-industriales\/configuraciones\/planta-peletizadora-media-1-plt200-400\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/peletizadoras.net\/es-ar\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/peletizadoras.net\/tienda\/"},{"@type":"ListItem","position":3,"name":"Planta Peletizadora Media 1 PLT200\/400"}]},{"@type":"WebSite","@id":"https:\/\/peletizadoras.net\/es-ar\/#website","url":"https:\/\/peletizadoras.net\/es-ar\/","name":"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","description":"Plantas y L\u00edneas industriales de peletizaci\u00f3n y m\u00e1quinas de fabricaci\u00f3n de pellet","publisher":{"@id":"https:\/\/peletizadoras.net\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/peletizadoras.net\/es-ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/peletizadoras.net\/es-ar\/#organization","name":"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","url":"https:\/\/peletizadoras.net\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/peletizadoras.net\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/05\/logo-ecofricalia-tapasweb.png","contentUrl":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/05\/logo-ecofricalia-tapasweb.png","width":881,"height":418,"caption":"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet"},"image":{"@id":"https:\/\/peletizadoras.net\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EcofricaliaSostenible","https:\/\/x.com\/_ecofricalia","https:\/\/www.youtube.com\/channel\/UCCvdG5pWUGvH4G5wP8TXuPw","https:\/\/www.instagram.com\/ecofricalia_sostenible\/"]}]}},"_links":{"self":[{"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product\/102268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/media\/102102"}],"wp:attachment":[{"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/media?parent=102268"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product_brand?post=102268"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product_cat?post=102268"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product_tag?post=102268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}