{"id":102304,"date":"2025-02-23T14:04:21","date_gmt":"2025-02-23T13:04:21","guid":{"rendered":"https:\/\/peletizadoras.net\/catalogo-maquinas-proceso-peletizado\/sin%20categor\u00eda\/grupos-electrogenos-hyundai-y-kompak\/"},"modified":"2025-12-03T12:10:55","modified_gmt":"2025-12-03T11:10:55","slug":"grupos-electrogenos-hyundai-y-kompak","status":"publish","type":"product","link":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/","title":{"rendered":"Grupos electr\u00f3genos Hyundai y Kompak"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>GENERADOR EL\u00c9CTRICO A LA MEDIDA DE SUS NECESIDADES<\/p>\n<p>Cuando no es posible o no se desea accionar la planta con toma el\u00e9ctrica directa, existen otras posibilidades. Desde Ecofricalia ponemos a disposici\u00f3n de nuestros clientes grupos electr\u00f3genos de las casas HYUNDAI y KOMPAK. <\/p>\n<p>Disponibilidad de una amplia gama de grupos electr\u00f3genos para lograr un perfecto funcionamiento en cada configuraci\u00f3n de peletizado.<\/p>\n","protected":false},"featured_media":101737,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[98],"product_tag":[104,105,106],"class_list":{"0":"post-102304","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-equipos-complementarios","7":"product_tag-generador-electrico-es-ar","8":"product_tag-grupo-electrogeno-es-ar","9":"product_tag-peletizado-es-ar","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grupos electr\u00f3genos Hyundai y Kompak - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet<\/title>\n<meta name=\"description\" content=\"Grupos electr\u00f3genos Hyundai para accionar las plantas de peletizado en aquellos lugares en donde no es posible usar la red el\u00e9ctrica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grupos electr\u00f3genos Hyundai y Kompak - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\" \/>\n<meta property=\"og:description\" content=\"Grupos electr\u00f3genos Hyundai para accionar las plantas de peletizado en aquellos lugares en donde no es posible usar la red el\u00e9ctrica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/\" \/>\n<meta property=\"og:site_name\" content=\"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EcofricaliaSostenible\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T11:10:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/grupo-electrogeno_90kva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@_ecofricalia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-complementarios\\\/grupos-electrogenos-hyundai-y-kompak\\\/\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-complementarios\\\/grupos-electrogenos-hyundai-y-kompak\\\/\",\"name\":\"Grupos electr\u00f3genos Hyundai y Kompak - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-complementarios\\\/grupos-electrogenos-hyundai-y-kompak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-complementarios\\\/grupos-electrogenos-hyundai-y-kompak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/grupo-electrogeno_90kva.jpg\",\"datePublished\":\"2025-02-23T13:04:21+00:00\",\"dateModified\":\"2025-12-03T11:10:55+00:00\",\"description\":\"Grupos electr\u00f3genos Hyundai para accionar las plantas de peletizado en aquellos lugares en donde no es posible usar la red el\u00e9ctrica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-complementarios\\\/grupos-electrogenos-hyundai-y-kompak\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-complementarios\\\/grupos-electrogenos-hyundai-y-kompak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-complementarios\\\/grupos-electrogenos-hyundai-y-kompak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/grupo-electrogeno_90kva.jpg\",\"contentUrl\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/grupo-electrogeno_90kva.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/catalogo-maquinas-proceso-peletizado\\\/equipos-complementarios\\\/grupos-electrogenos-hyundai-y-kompak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/peletizadoras.net\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grupos electr\u00f3genos Hyundai y Kompak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#website\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/\",\"name\":\"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\",\"description\":\"Plantas y L\u00edneas industriales de peletizaci\u00f3n y m\u00e1quinas de fabricaci\u00f3n de pellet\",\"publisher\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#organization\",\"name\":\"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-ecofricalia-tapasweb.png\",\"contentUrl\":\"https:\\\/\\\/peletizadoras.net\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-ecofricalia-tapasweb.png\",\"width\":881,\"height\":418,\"caption\":\"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet\"},\"image\":{\"@id\":\"https:\\\/\\\/peletizadoras.net\\\/es-ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EcofricaliaSostenible\",\"https:\\\/\\\/x.com\\\/_ecofricalia\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCCvdG5pWUGvH4G5wP8TXuPw\",\"https:\\\/\\\/www.instagram.com\\\/ecofricalia_sostenible\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grupos electr\u00f3genos Hyundai y Kompak - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","description":"Grupos electr\u00f3genos Hyundai para accionar las plantas de peletizado en aquellos lugares en donde no es posible usar la red el\u00e9ctrica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/","og_locale":"es_ES","og_type":"article","og_title":"Grupos electr\u00f3genos Hyundai y Kompak - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","og_description":"Grupos electr\u00f3genos Hyundai para accionar las plantas de peletizado en aquellos lugares en donde no es posible usar la red el\u00e9ctrica","og_url":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/","og_site_name":"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","article_publisher":"https:\/\/www.facebook.com\/EcofricaliaSostenible","article_modified_time":"2025-12-03T11:10:55+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/grupo-electrogeno_90kva.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@_ecofricalia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/","url":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/","name":"Grupos electr\u00f3genos Hyundai y Kompak - Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","isPartOf":{"@id":"https:\/\/peletizadoras.net\/es-ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/#primaryimage"},"image":{"@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/#primaryimage"},"thumbnailUrl":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/grupo-electrogeno_90kva.jpg","datePublished":"2025-02-23T13:04:21+00:00","dateModified":"2025-12-03T11:10:55+00:00","description":"Grupos electr\u00f3genos Hyundai para accionar las plantas de peletizado en aquellos lugares en donde no es posible usar la red el\u00e9ctrica","breadcrumb":{"@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/#primaryimage","url":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/grupo-electrogeno_90kva.jpg","contentUrl":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/02\/grupo-electrogeno_90kva.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/peletizadoras.net\/es-ar\/catalogo-maquinas-proceso-peletizado\/equipos-complementarios\/grupos-electrogenos-hyundai-y-kompak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/peletizadoras.net\/es-ar\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/peletizadoras.net\/tienda\/"},{"@type":"ListItem","position":3,"name":"Grupos electr\u00f3genos Hyundai y Kompak"}]},{"@type":"WebSite","@id":"https:\/\/peletizadoras.net\/es-ar\/#website","url":"https:\/\/peletizadoras.net\/es-ar\/","name":"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","description":"Plantas y L\u00edneas industriales de peletizaci\u00f3n y m\u00e1quinas de fabricaci\u00f3n de pellet","publisher":{"@id":"https:\/\/peletizadoras.net\/es-ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/peletizadoras.net\/es-ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/peletizadoras.net\/es-ar\/#organization","name":"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet","url":"https:\/\/peletizadoras.net\/es-ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/peletizadoras.net\/es-ar\/#\/schema\/logo\/image\/","url":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/05\/logo-ecofricalia-tapasweb.png","contentUrl":"https:\/\/peletizadoras.net\/wp-content\/uploads\/2025\/05\/logo-ecofricalia-tapasweb.png","width":881,"height":418,"caption":"Ecofricalia. Soluciones Integrales para la Producci\u00f3n de Pellet"},"image":{"@id":"https:\/\/peletizadoras.net\/es-ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EcofricaliaSostenible","https:\/\/x.com\/_ecofricalia","https:\/\/www.youtube.com\/channel\/UCCvdG5pWUGvH4G5wP8TXuPw","https:\/\/www.instagram.com\/ecofricalia_sostenible\/"]}]}},"_links":{"self":[{"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product\/102304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/media\/101737"}],"wp:attachment":[{"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/media?parent=102304"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product_brand?post=102304"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product_cat?post=102304"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/peletizadoras.net\/es-ar\/wp-json\/wp\/v2\/product_tag?post=102304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}